{"id":121105,"date":"2017-05-15T00:00:00","date_gmt":"2017-05-14T22:00:00","guid":{"rendered":"https:\/\/www.mdirector.com\/2018\/08\/06\/crea-un-template-di-email-marketing-da-zero\/"},"modified":"2024-03-12T12:58:36","modified_gmt":"2024-03-12T11:58:36","slug":"crea-un-template-di-email-marketing-da-zero","status":"publish","type":"post","link":"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/","title":{"rendered":"Crea un template di email marketing da zero"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div><p><link rel=\"preload\" as=\"image\" href=\"https:\/\/www.mdirector.com\/wp-content\/uploads\/2022\/04\/plantillas-mdirector-academy-ok2-1.png\" imagesizes=\"(max-width: 1100px) 100vw, 1100px\" \/><img decoding=\"async\" class=\"aligncenter wp-image-72993 size-full\" src=\"https:\/\/www.mdirector.com\/wp-content\/uploads\/2022\/04\/plantillas-mdirector-academy-ok2-1.png\" alt=\"\" width=\"800\" height=\"401\" \/><\/p>\n<p><strong>\u00c8 arrivato il momento e devi sapere come creare un template di email marketing per attivare le tue campagne.<\/strong> Ma sai come farlo? Da dove cominciare? Ti chiedi se \u00e8 necessario avere conoscenze tecniche e di grafica per creare un buon template email?<\/p>\n<p>Come responsabile marketing stai famigliarizzando con il ciclo di produzione che richiede ogni nuova campagna. Quando attivi la prima \u00e8 gi\u00e0 ora di pensare alla successiva e molte volte rompere questo ciclo per dedicarti ai dettagli \u00e8 quasi impossibile.<\/p>\n<p>Nonostante questa sfida, ci sono trucchi e alternative per guadagnare tempo e ottenere risultati di successo. Quindi se ti chiedi come creare un template di email marketing a seguire ti segnaliamo alcuni passaggi essenziali. Inoltre ricorda che potrai salvarlo e usarlo successivamente.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_74 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">INDICE DEI CONTENUTI<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#Best_practices_per_determinare_come_creare_un_template_di_email_marketing\" >Best practices per determinare come creare un template di email marketing<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#Principi_generali_di_grafica\" >Principi generali di grafica<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#Immagini\" >Immagini<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#Links\" >Links<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#Come_creare_un_template_di_email_marketing_da_zero\" >Come creare un template di email marketing da zero?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#Template_za_zero\" >Template za zero<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#1-_Definisci_lo_stile_del_tuo_template\" >1.- Definisci lo stile del tuo template<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#2-_Decidi_come_sara_la_distribuzione\" >2.- Decidi come sar\u00e0 la distribuzione<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#3-_Comincia_con_lintestazione\" >3.- Comincia con l\u2019intestazione<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#4-_Prosegui_con_il_contenuto\" >4.- Prosegui con il contenuto<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#5-_Includi_i_social_e_il_footer\" >5.- Includi i social e il footer<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#6-_Fai_un_AB_test_e_valuta_i_risultati\" >6.- Fai un A\/B test e valuta i risultati<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#2-_Template_precostruiti\" >2.- Template precostruiti<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#Nel_caso_tu_scelga_un_template_specifico_devi_assicurarti_che_rispetti_alcuni_requisiti\" >Nel caso tu scelga un template specifico devi assicurarti che rispetti alcuni requisiti<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Best_practices_per_determinare_come_creare_un_template_di_email_marketing\"><\/span>Best practices per determinare come creare un template di email marketing<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img decoding=\"async\" class=\"wp-image-72978 size-full aligncenter\" src=\"https:\/\/www.mdirector.com\/wp-content\/uploads\/2022\/04\/como-crear-una-plantilla-de-email-2-1.png\" alt=\"\" width=\"1013\" height=\"658\" \/><\/p>\n<p>Uno dei compiti pi\u00f9 gratificanti di una strategia di digital marketing \u00e8 determinare come creare un template di email che successivamente riceveranno gli utenti.<\/p>\n<p>Ma \u00e8 necessario compiere alcuni passi e utilizzare alcune best practices per assicurarti che i tuoi messaggi vengano mostrati correttamente. Altrimenti tutta la strategia sar\u00e0 stata creata invano.<\/p>\n<p>Da qui l\u2019importanza del disporre di diversi template precostruiti che ti permettano di focalizzare gli sforzi su ogni messaggio e non su mere questioni grafiche. Ossia, pensi che puoi permetterti di decidere il tipo di font, il colore o la forma che deve avere la tua mail ogni volta che ne invii una? <strong>Normalmente devi seguire le linee guida della tua corporate image.<\/strong><\/p>\n[bannerHeroIT]\n<p>Anche cos\u00ec, considera che tutti i template devono seguire alcune regole. Per questo devi considerare le seguenti best practices, con cui ti assicurerai la visibilit\u00e0 dei tuoi messaggi e il fatto che il contenuto sia efficace.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Principi_generali_di_grafica\"><\/span>Principi generali di grafica:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><strong>-Grafica a riquadri.<\/strong> La maggior parte dei client non supporta le etichette\n<div>. Quindi ti consigliamo di utilizzare i riquadri per dividere gli elementi delle mail.<\/div>\n<\/li>\n<li><strong>-Specifica la larghezza.<\/strong> L\u2019ideale \u00e8 stabilire una larghezza specifica per ogni elemento.<\/li>\n<li>-Molti dei <strong>principali client di email non supportano margini.<\/strong> Per evitarlo, utiliza riquadri che permettono di inserire immagini e testi.<\/li>\n<li>-Per una massima visibilit\u00e0, l\u2019ideale \u00e8 che le tue grafiche misurino<strong> 600 pixels di larghezza<\/strong><\/li>\n<li>-Dall\u2019altro lato <strong>alcuni dei principali client email come Outlook, non supportano CSS.<\/strong><\/li>\n<li><strong>-Definisci gli stili di ogni testo,<\/strong> includendo font, dimensioni e colori.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Immagini\"><\/span>Immagini<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Esistono alcune best practices da considerare che sono specifiche nel caso in cui utilizzi immagini nelle mail HTML:<\/p>\n<ul>\n<li><strong>-Evita di utilizzare troppe immagini.<\/strong> <a href=\"https:\/\/www.mdirector.com\/it\/email-marketing-it\/tipi-filtri-antispam-esistono.html\" target=\"_blank\" rel=\"noopener noreferrer\">Alcuni filtri<\/a> anti spam considerano che i messaggi che pesano molto come non desiderati.<\/li>\n<li><strong>-Includi alt tag in ogni immagine e utilizza URLs uniche<\/strong> per ubicarle.<\/li>\n<li>&#8211;<strong>Specifica altezza e larghezza<\/strong> delle immagini.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Links\"><\/span>Links<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Utilizza sempre URLs univoche per ogni link. Ossia indica sempre tutto il percorso di ogni link.<\/p>\n<p>Evita di linkare immagini<\/p>\n<p>Non abusare dei links. Se ne utilizzi molti, alcuni filtri potrebbero considerarli spam e pregiudicare l\u2019esito delle tue campagne.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Come_creare_un_template_di_email_marketing_da_zero\"><\/span>Come creare un template di email marketing da zero?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"su-youtube su-u-responsive-media-yes\"><iframe width=\"700\" height=\"440\" src=\"https:\/\/www.youtube.com\/embed\/wDGt09ysNHw?autohide=2&amp;autoplay=0&amp;mute=0&amp;controls=1&amp;fs=1&amp;loop=0&amp;modestbranding=0&amp;rel=1&amp;showinfo=1&amp;theme=dark&amp;wmode=&amp;playsinline=0\" frameborder=\"0\" allowfullscreen allow=\"autoplay; encrypted-media; picture-in-picture\" title=\"\"><\/iframe><\/div>\nPrima di tutto devi avere chiaro che un\u2019email non \u00e8 un sito. Hanno fini e caratteristiche diversi. Di fatto un <strong>messaggio email serve per entrare in contatto con l\u2019utente in maniera rapida e informale riguardo a questioni concrete.<\/strong> Se il cliente desiderasse pi\u00f9 informazioni dovrebbe cliccare sul contenuto del messaggio e continuare la navigazione fino alla landing page predefinita.<\/p>\n<p>Arrivato a questo punto hai due opzioni:<\/p>\n<ul>\n<li><strong>Creare un template da zero<\/strong><\/li>\n<li><a href=\"https:\/\/www.mdirector.com\/it\/email-marketing\/galleria-di-modelli-tematici-per-email-marketing\/\" target=\"_blank\" rel=\"noopener noreferrer\">Basarti su template gi\u00e0 creati<\/a> e lavorare su di essi per personalizzarli<\/li>\n<\/ul>\n<ol>\n<li>\n<h3><span class=\"ez-toc-section\" id=\"Template_za_zero\"><\/span>Template za zero<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<\/li>\n<\/ol>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-72983 size-full\" src=\"https:\/\/www.mdirector.com\/wp-content\/uploads\/2022\/04\/como-crear-una-plantilla-de-email-3-1.png\" alt=\"\" width=\"830\" height=\"540\" \/><\/p>\n<p>Se vuoi cominciare da zero ti consigliamo di utilizzare l\u2019<a href=\"https:\/\/www.mdirector.com\/it\/signup-email-marketing\/?\" target=\"_blank\" rel=\"noopener noreferrer\">editor di MDirector<\/a>. <strong>Ti risulter\u00e0 molto semplice trovare gli elementi per determinare come creare un template di email efficace, interessante e particolare.<\/strong> \u00c8 facile come seguire i primi passi:<\/p>\n<h4><span class=\"ez-toc-section\" id=\"1-_Definisci_lo_stile_del_tuo_template\"><\/span>1.- Definisci lo stile del tuo template<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul>\n<li><strong>Sfondo.<\/strong> Pu\u00f2 essere colorato o un\u2019immagine. Ma l\u2019immagine non \u00e8 consigliabile. Come sai Outlook non lo permette. Inoltre a livello di grafica la lettura non \u00e8 mai ottimale.<\/li>\n<li><strong>Testo.<\/strong> Puoi definire i font che userai nella tua grafica, la dimensione, lo spessore e il colore.<\/li>\n<li><strong>Link.<\/strong> Puoi personalizzare i link mettendoli in un colore determinato. Se sei in linea con le tue linee guida, meglio.<\/li>\n<li><strong>Titolo.<\/strong> Riguarda solo i titoli principali H1.<\/li>\n<li><strong>Bordo.<\/strong> Tutte le newsletter sono create mediante blocchi. Il bordo del blocco si pu\u00f2 personalizzare scegliendo il colore, il raggio, la larghezza e lo stile.<\/li>\n<\/ul>\n<h4><span class=\"ez-toc-section\" id=\"2-_Decidi_come_sara_la_distribuzione\"><\/span><strong>2.- Decidi come sar\u00e0 la distribuzione<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Ti consigliamo di inserire prima l\u2019intestazione. A seguire ci sono il logo e il contenuto. In questo caso, per utilizzare l\u2019editor di MDirector ti consigliamo di <a href=\"https:\/\/mdirector.zendesk.com\/hc\/it\/articles\/203967272-Template-Dimensioni-immagini\" target=\"_blank\" rel=\"noopener noreferrer\">consultare i suoi requisiti<\/a> e sapere quali dimensioni seguire.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"3-_Comincia_con_lintestazione\"><\/span>3.- Comincia con l\u2019intestazione<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Quale elemento non pu\u00f2 mancare? Il logo. Non puoi pensare di non includere un link nel logo che porti l\u2019utente al tuo sito. Inoltre anche l\u2019intestazione include un titolo e un elemento separatore che puoi personalizzare.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"4-_Prosegui_con_il_contenuto\"><\/span>4.- Prosegui con il contenuto<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Potrai editare la struttura, il contenuto che viene incluso nella mail o anche i pulsanti della call to action. Inoltre uno dei punti forti dell\u2019editor di MDirector \u00e8 che nel c<strong>aso in cui il contenuto sia troppo lungo, lo adatter\u00e0 automaticamente.<\/strong><\/p>\n<h4><span class=\"ez-toc-section\" id=\"5-_Includi_i_social_e_il_footer\"><\/span>5.- Includi i social e il footer<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Seleziona i social che hai attivi. Successivamente ricorda di aggiungere i link e personalizzare lo stile in base alla tua grafica.<\/p>\n[bannerHeroIT]\n<h4><span class=\"ez-toc-section\" id=\"6-_Fai_un_AB_test_e_valuta_i_risultati\"><\/span>6.- Fai un A\/B test e valuta i risultati<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><strong>Non dimenticarti mai di fare prove per assicurarti che il tuo template non possa essere migliorato.<\/strong> <a href=\"https:\/\/www.mdirector.com\/it\/email-marketing\/test-ab-ottimizzatore-di-campagne\/\" target=\"_blank\" rel=\"noopener noreferrer\">Gli A\/B<\/a> test non solo ti permettono di valutare che la tua grafica si veda correttamente attraverso i diversi devices ma ti permettono anche di assicurarti la consegna nella posta in entrata degli utenti.<\/p>\n<p>Con i risultati valutabili potrai fare le correzioni necessarie per confermare l\u2019invio definitivo.<\/p>\n<p>Inoltre, se sei un professionista del codice e conosci i trucchi per creare direttamente un template per email puoi farlo direttamente dall\u2019editor avanzato in HTML.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"2-_Template_precostruiti\"><\/span><strong>2.- Template precostruiti<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-72988 size-full\" src=\"https:\/\/www.mdirector.com\/wp-content\/uploads\/2022\/04\/como-crear-una-plantilla-de-email-5-1.jpg\" alt=\"\" width=\"689\" height=\"621\" \/><\/p>\n<p>Come hai visto, creare un template per email pu\u00f2 essere un\u2019attivit\u00e0 complessa. O molto semplice se sai come farlo. Per questo<strong> i template per email marketing sono una soluzione ideale per far emergere il tuo contenuto e evitare ore e ore di lavoro, risparmiando.<\/strong><\/p>\n<p>Strumenti come MDirector mettono a tua disposizione un ampio <a href=\"https:\/\/www.mdirector.com\/it\/email-marketing\/galleria-di-modelli-tematici-per-email-marketing\/\" target=\"_blank\" rel=\"noopener noreferrer\">catalogo di templates pronti per le tue mail.<\/a> Divisi per categoria e tematiche, i template precostruiti possono essere la soluzione per creare email in breve tempo e poche risorse.<\/p>\n<p>Inoltre, tutti i templates sono modificabili per cui puoi adattare totalmente il look &amp; feel della tua attivit\u00e0 e sono disponibili in versione desktop o<a href=\"https:\/\/www.mdirector.com\/it\/email-marketing\/design-reattivo-per-email-marketing\/\" target=\"_blank\" rel=\"noopener noreferrer\"> mobile.<\/a><\/p>\n<p>Fattori che un template di email deve rispettare<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Nel_caso_tu_scelga_un_template_specifico_devi_assicurarti_che_rispetti_alcuni_requisiti\"><\/span>Nel caso tu scelga un template specifico devi assicurarti che rispetti alcuni requisiti:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><strong>Semplicit\u00e0.<\/strong> \u00c8 importate rendere la vita facile all\u2019utente.<strong> Ogni template efficace \u00e8 legato a un modello semplice e consistente.<\/strong> Per esempio i templates a colonna sono pi\u00f9 semplici da visualizzare. Inoltre non conviene sovraccaricare il template con molte immagini dato che aumenter\u00e0 il peso che pu\u00f2 rallentare il caricamento e aumentare le possibilit\u00e0 che l\u2019utente non riceva il messaggio nella posta in entrata.<\/li>\n<li><strong>Un\u2019identit\u00e0 corporate chiara.<\/strong> Non ha senso utilizzare un template che non corrisponda al branding aziendale. Il template che utilizzi deve rispettare <strong>i colori corporate, includere il tuo logo adattato e considerare i font che definiscono il brand.<\/strong><\/li>\n<li><strong>Grafica responsive.<\/strong> Il tasso di apertura delle mail da dispositivi mobile \u00e8 aumentato del 180% negli ultimi 3 anni secondo <a href=\"https:\/\/www.socialmediatoday.com\/marketing\/8-mobile-marketing-stats-help-you-plan-2016\" target=\"_blank\" rel=\"noopener noreferrer\">SocialMediaToday<\/a>. L\u2019adattamento non deve essere solo per gli elementi tecnici ma anche per i contenuti in cui includi il messaggio. Per esempio, utilizzando una dimensione maggiore del font.<\/li>\n<\/ul>\n<p>Tutti i template per email marketing sono a tua disposizione su <strong>MDirector.<\/strong> Prova il nostro <a href=\"https:\/\/www.mdirector.com\/it\/email-marketing\/\" target=\"_blank\" rel=\"noopener noreferrer\">strumento di email marketing<\/a> e comincia a lavorare con questi magnifici templates tematici gratuiti. Sono tutti modificabili e editabili. Per questo MDirector \u00e8 la soluzione ideale determinare come creare un template di email e ottimizzare gli invii.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 arrivato il momento e devi sapere come creare un template di email marketing per attivare le tue campagne. Ma sai come farlo? Da dove cominciare? Ti chiedi se \u00e8 necessario avere conoscenze tecniche e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":41635,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","rating_form_position":"","rating_results_position":"","mr_structured_data_type":"","footnotes":""},"categories":[1885],"tags":[],"class_list":["post-121105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-email-marketing"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Crea un template di email marketing da zero<\/title>\n<meta name=\"description\" content=\"\u00c8 arrivato il momento e devi sapere come creare un template di email marketing per attivare le tue campagne. Ma sai come farlo? Da dove cominciare? Ti\" \/>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crea un template di email marketing da zero\" \/>\n<meta property=\"og:description\" content=\"\u00c8 arrivato il momento e devi sapere come creare un template di email marketing per attivare le tue campagne. Ma sai come farlo? Da dove cominciare? Ti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/\" \/>\n<meta property=\"og:site_name\" content=\"MDirector\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MDirector.es\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-14T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-12T11:58:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mdirector.com\/wp-content\/uploads\/2022\/04\/editor-email-mdirector-cabecera-2-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"653\" \/>\n\t<meta property=\"og:image:height\" content=\"493\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"NewsMDirector\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emailMDirector\" \/>\n<meta name=\"twitter:site\" content=\"@emailMDirector\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"NewsMDirector\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/\"},\"author\":{\"name\":\"NewsMDirector\",\"@id\":\"https:\/\/www.mdirector.com\/it\/#\/schema\/person\/d91d62ca88afe0ab43d79d7fadc367b5\"},\"headline\":\"Crea un template di email marketing da zero\",\"datePublished\":\"2017-05-14T22:00:00+00:00\",\"dateModified\":\"2024-03-12T11:58:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/\"},\"wordCount\":1333,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.mdirector.com\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mdirector.com\/wp-content\/uploads\/2022\/04\/editor-email-mdirector-cabecera-2-1.png\",\"articleSection\":[\"Email Marketing\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/\",\"url\":\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/\",\"name\":\"Crea un template di email marketing da zero\",\"isPartOf\":{\"@id\":\"https:\/\/www.mdirector.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mdirector.com\/wp-content\/uploads\/2022\/04\/editor-email-mdirector-cabecera-2-1.png\",\"datePublished\":\"2017-05-14T22:00:00+00:00\",\"dateModified\":\"2024-03-12T11:58:36+00:00\",\"description\":\"\u00c8 arrivato il momento e devi sapere come creare un template di email marketing per attivare le tue campagne. Ma sai come farlo? Da dove cominciare? Ti\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#primaryimage\",\"url\":\"https:\/\/www.mdirector.com\/wp-content\/uploads\/2022\/04\/editor-email-mdirector-cabecera-2-1.png\",\"contentUrl\":\"https:\/\/www.mdirector.com\/wp-content\/uploads\/2022\/04\/editor-email-mdirector-cabecera-2-1.png\",\"width\":653,\"height\":493},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.mdirector.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Email Marketing\",\"item\":\"https:\/\/www.mdirector.com\/it\/blog\/email-marketing\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Crea un template di email marketing da zero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mdirector.com\/it\/#website\",\"url\":\"https:\/\/www.mdirector.com\/it\/\",\"name\":\"MDirector\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.mdirector.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mdirector.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.mdirector.com\/it\/#organization\",\"name\":\"MDirector\",\"url\":\"https:\/\/www.mdirector.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.mdirector.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.mdirector.com\/wp-content\/uploads\/2023\/01\/mdirectorbimi-ok23-tiny-ps.svg\",\"contentUrl\":\"https:\/\/www.mdirector.com\/wp-content\/uploads\/2023\/01\/mdirectorbimi-ok23-tiny-ps.svg\",\"width\":401,\"height\":401,\"caption\":\"MDirector\"},\"image\":{\"@id\":\"https:\/\/www.mdirector.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MDirector.es\",\"https:\/\/x.com\/emailMDirector\",\"https:\/\/www.linkedin.com\/company\/1373906\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.mdirector.com\/it\/#\/schema\/person\/d91d62ca88afe0ab43d79d7fadc367b5\",\"name\":\"NewsMDirector\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.mdirector.com\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/56aaa057e6c30e70ef9a4db165a17832a7661affd8b3677bf17f63d57e8adf60?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/56aaa057e6c30e70ef9a4db165a17832a7661affd8b3677bf17f63d57e8adf60?s=96&d=mm&r=g\",\"caption\":\"NewsMDirector\"},\"description\":\"Equipo de Redacci\u00f3n de MDirector\",\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/1373906\"],\"url\":\"https:\/\/www.mdirector.com\/it\/author\/newsmdirector\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crea un template di email marketing da zero","description":"\u00c8 arrivato il momento e devi sapere come creare un template di email marketing per attivare le tue campagne. Ma sai come farlo? Da dove cominciare? Ti","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/","og_locale":"it_IT","og_type":"article","og_title":"Crea un template di email marketing da zero","og_description":"\u00c8 arrivato il momento e devi sapere come creare un template di email marketing per attivare le tue campagne. Ma sai come farlo? Da dove cominciare? Ti","og_url":"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/","og_site_name":"MDirector","article_publisher":"https:\/\/www.facebook.com\/MDirector.es","article_published_time":"2017-05-14T22:00:00+00:00","article_modified_time":"2024-03-12T11:58:36+00:00","og_image":[{"width":653,"height":493,"url":"https:\/\/www.mdirector.com\/wp-content\/uploads\/2022\/04\/editor-email-mdirector-cabecera-2-1.png","type":"image\/png"}],"author":"NewsMDirector","twitter_card":"summary_large_image","twitter_creator":"@emailMDirector","twitter_site":"@emailMDirector","twitter_misc":{"Scritto da":"NewsMDirector","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#article","isPartOf":{"@id":"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/"},"author":{"name":"NewsMDirector","@id":"https:\/\/www.mdirector.com\/it\/#\/schema\/person\/d91d62ca88afe0ab43d79d7fadc367b5"},"headline":"Crea un template di email marketing da zero","datePublished":"2017-05-14T22:00:00+00:00","dateModified":"2024-03-12T11:58:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/"},"wordCount":1333,"commentCount":0,"publisher":{"@id":"https:\/\/www.mdirector.com\/it\/#organization"},"image":{"@id":"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mdirector.com\/wp-content\/uploads\/2022\/04\/editor-email-mdirector-cabecera-2-1.png","articleSection":["Email Marketing"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/","url":"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/","name":"Crea un template di email marketing da zero","isPartOf":{"@id":"https:\/\/www.mdirector.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#primaryimage"},"image":{"@id":"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mdirector.com\/wp-content\/uploads\/2022\/04\/editor-email-mdirector-cabecera-2-1.png","datePublished":"2017-05-14T22:00:00+00:00","dateModified":"2024-03-12T11:58:36+00:00","description":"\u00c8 arrivato il momento e devi sapere come creare un template di email marketing per attivare le tue campagne. Ma sai come farlo? Da dove cominciare? Ti","breadcrumb":{"@id":"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#primaryimage","url":"https:\/\/www.mdirector.com\/wp-content\/uploads\/2022\/04\/editor-email-mdirector-cabecera-2-1.png","contentUrl":"https:\/\/www.mdirector.com\/wp-content\/uploads\/2022\/04\/editor-email-mdirector-cabecera-2-1.png","width":653,"height":493},{"@type":"BreadcrumbList","@id":"https:\/\/www.mdirector.com\/it\/blog\/crea-un-template-di-email-marketing-da-zero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.mdirector.com\/it\/"},{"@type":"ListItem","position":2,"name":"Email Marketing","item":"https:\/\/www.mdirector.com\/it\/blog\/email-marketing\/"},{"@type":"ListItem","position":3,"name":"Crea un template di email marketing da zero"}]},{"@type":"WebSite","@id":"https:\/\/www.mdirector.com\/it\/#website","url":"https:\/\/www.mdirector.com\/it\/","name":"MDirector","description":"","publisher":{"@id":"https:\/\/www.mdirector.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mdirector.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.mdirector.com\/it\/#organization","name":"MDirector","url":"https:\/\/www.mdirector.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.mdirector.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.mdirector.com\/wp-content\/uploads\/2023\/01\/mdirectorbimi-ok23-tiny-ps.svg","contentUrl":"https:\/\/www.mdirector.com\/wp-content\/uploads\/2023\/01\/mdirectorbimi-ok23-tiny-ps.svg","width":401,"height":401,"caption":"MDirector"},"image":{"@id":"https:\/\/www.mdirector.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MDirector.es","https:\/\/x.com\/emailMDirector","https:\/\/www.linkedin.com\/company\/1373906\/"]},{"@type":"Person","@id":"https:\/\/www.mdirector.com\/it\/#\/schema\/person\/d91d62ca88afe0ab43d79d7fadc367b5","name":"NewsMDirector","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.mdirector.com\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/56aaa057e6c30e70ef9a4db165a17832a7661affd8b3677bf17f63d57e8adf60?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56aaa057e6c30e70ef9a4db165a17832a7661affd8b3677bf17f63d57e8adf60?s=96&d=mm&r=g","caption":"NewsMDirector"},"description":"Equipo de Redacci\u00f3n de MDirector","sameAs":["https:\/\/www.linkedin.com\/company\/1373906"],"url":"https:\/\/www.mdirector.com\/it\/author\/newsmdirector\/"}]}},"modified_by":null,"multi-rating":{"mr_rating_results":[]},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.mdirector.com\/it\/wp-json\/wp\/v2\/posts\/121105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mdirector.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mdirector.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mdirector.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mdirector.com\/it\/wp-json\/wp\/v2\/comments?post=121105"}],"version-history":[{"count":0,"href":"https:\/\/www.mdirector.com\/it\/wp-json\/wp\/v2\/posts\/121105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mdirector.com\/it\/wp-json\/wp\/v2\/media\/41635"}],"wp:attachment":[{"href":"https:\/\/www.mdirector.com\/it\/wp-json\/wp\/v2\/media?parent=121105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mdirector.com\/it\/wp-json\/wp\/v2\/categories?post=121105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mdirector.com\/it\/wp-json\/wp\/v2\/tags?post=121105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}